{"id":3533,"date":"2025-08-08T10:55:07","date_gmt":"2025-08-08T08:55:07","guid":{"rendered":"https:\/\/amblavalletta.esteri.it\/?p=3533"},"modified":"2025-08-08T11:19:55","modified_gmt":"2025-08-08T09:19:55","slug":"messaggio-del-vice-presidente-del-consiglio-dei-ministri-e-ministro-degli-affari-esteri-e-cooperazione-internazionale-on-antonio-tajani-in-occasione-del-69-anniversario-del-disastro-di-marcin","status":"publish","type":"post","link":"https:\/\/amblavalletta.esteri.it\/it\/news\/dall_ambasciata\/2025\/08\/messaggio-del-vice-presidente-del-consiglio-dei-ministri-e-ministro-degli-affari-esteri-e-cooperazione-internazionale-on-antonio-tajani-in-occasione-del-69-anniversario-del-disastro-di-marcin\/","title":{"rendered":"MESSAGGIO DEL VICE PRESIDENTE DEL CONSIGLIO DEI MINISTRI E MINISTRO DEGLI AFFARI ESTERI E COOPERAZIONE INTERNAZIONALE, ON. ANTONIO TAJANI, IN OCCASIONE DEL 69\u00b0 ANNIVERSARIO DEL DISASTRO DI MARCINELLE, E LA 24\u00b0 GIORNATA NAZIONALE DEL SACRIFICIO DEL LAVORO ITALIANO NEL MONDO"},"content":{"rendered":"<div class=\"n4sEPd\">\n<div class=\"QFw9Te BLojaf\">Il Vice Presidente del Consiglio dei Ministri e Ministro degli Affari Esteri e Cooperazione Internazionale, On. Antonio Tajani, in occasione del 69\u00b0 anniversario del disastro di Marcinelle, e la 24\u00aa Giornata Nazionale del sacrificio del lavoro italiano nel mondo, ha inviato il seguente messaggio:\u00a0 \u00a0\u00a0<a href=\"https:\/\/ambbruxelles.esteri.it\/wp-content\/uploads\/2025\/08\/MESSAGGIO-VP-TAJANI-GIORNATA-DEL-SACRIFICIO-DEL-LAVORO-ITALIANO_1.pdf\">clicca qui<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Il Vice Presidente del Consiglio dei Ministri e Ministro degli Affari Esteri e Cooperazione Internazionale, On. Antonio Tajani, in occasione del 69\u00b0 anniversario del disastro di Marcinelle, e la 24\u00aa Giornata Nazionale del sacrificio del lavoro italiano nel mondo, ha inviato il seguente messaggio:\u00a0 \u00a0\u00a0clicca qui","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-3533","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/amblavalletta.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amblavalletta.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amblavalletta.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amblavalletta.esteri.it\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/amblavalletta.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=3533"}],"version-history":[{"count":3,"href":"https:\/\/amblavalletta.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3533\/revisions"}],"predecessor-version":[{"id":3543,"href":"https:\/\/amblavalletta.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3533\/revisions\/3543"}],"wp:attachment":[{"href":"https:\/\/amblavalletta.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=3533"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amblavalletta.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=3533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}